{"id":73,"date":"2015-09-12T01:18:40","date_gmt":"2015-09-12T01:18:40","guid":{"rendered":"http:\/\/www.words.vasnfer.com\/?p=73"},"modified":"2016-05-27T17:29:28","modified_gmt":"2016-05-27T17:29:28","slug":"o-amor-nao-olha-a-deficiencias-ou-estigmas","status":"publish","type":"post","link":"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/","title":{"rendered":"O amor n\u00e3o olha a defici\u00eancias ou estigmas &#8230;"},"content":{"rendered":"<h6 style=\"text-align: justify;\">Faz uns meses, que enquanto tomava um caf\u00e9 numa esplanada algures em Portugal tomei contacto com a hist\u00f3ria que aqui irei relatar nas pr\u00f3ximas linhas.<\/h6>\n<h3 style=\"text-align: justify;\">Ser\u00e1 o amor realmente cego ?<\/h3>\n<p style=\"text-align: justify;\">Ouvimos muitas vezes dizer que o amor n\u00e3o escolhe idades, que n\u00e3o escolhe entre ra\u00e7as e que acima de tudo n\u00e3o escolhe a perfei\u00e7\u00e3o. Pois bem achei uma hist\u00f3ria muito curiosa e tive oportunidade de a aprofundar com os dois &#8220;actores&#8221; principais desse romance da Vida real.<!--more--><\/p>\n<p style=\"text-align: justify;\">Poderia descreve-la em poucas palavras como um romance Shakespeariano ou uma hist\u00f3ria de pr\u00edncipes e princesas da produtora de Wall Disney, mas n\u00e3o a hist\u00f3ria \u00e9 toda ela bem real e passada aqui neste cantinho \u00e0 beira mar plantado.<\/p>\n<p style=\"text-align: justify;\">Ant\u00f3nio \u00e9 um rapaz jovem e esbelto na casa dos vinte e sete anos, com um emprego est\u00e1vel na \u00e1rea da engenharia e projec\u00e7\u00e3o de infra-estruturas de comunica\u00e7\u00e3o, e com um olhar de profunda paix\u00e3o pela sua pessoa amada faz sorrir quem passa nunca deixando que nada interfira na sua rela\u00e7\u00e3o que ultrapassa todos os limites da paix\u00e3o e do altru\u00edsmo diz ele num tom meio s\u00e9rio &#8220;se sou o que sou hoje e se luto por ser feliz \u00e9 porque tenho o prazer de acordar todos os dias ao lado do amor da minha Vida, e\u00a0tomar o pequeno almo\u00e7o\u00a0a olhar para o rosto de algu\u00e9m\u00a0me ama de igual forma\u00a0n\u00e3o \u00e9 uma obriga\u00e7\u00e3o \u00e9 um aut\u00eantico prazer que faz com que tempo esse seja relativo e aumentado &#8230;&#8221;, o seu sorriso \u00e9 contagiante em todos os n\u00edveis. Ant\u00f3nio \u00e9 tamb\u00e9m um homem de rotinas, confessa, sabe o nome de quase todas as pessoas que encontra na rua e no escrit\u00f3rio e o mais engra\u00e7ado diz &#8220;\u00e9 que as pessoas raramente sabem o meu nome, mas isso n\u00e3o me importa apenas quero que conhe\u00e7am o meu rosto e que tenham a oportunidade de ser felizes como eu tenho a minha &#8230;&#8221;. Ant\u00f3nio quando fala da sua &#8220;alma g\u00e9mea&#8221;, como afirma, os seus olhos ficam mais que radiantes e brilhantes do amor profundo que sente por esse tal algu\u00e9m. E por esta altura j\u00e1 se perguntam, mas a final quem \u00e9 esse tal algu\u00e9m?<\/p>\n<p style=\"text-align: justify;\">Este algu\u00e9m que faz brilhar os olhos de Ant\u00f3nio e que faz com que parte da sua rotina sejam exclusivamente dedicados a ele \u00e9, \u00a0Tiago um jovem de vinte e cinco anos, tamb\u00e9m com um emprego est\u00e1vel como chefe de opera\u00e7\u00f5es log\u00edsticas e coordena\u00e7\u00e3o de circula\u00e7\u00e3o, com uma apar\u00eancia complemente normal, mas com uma particularidade que afecta cerca de um e meio por cento da popula\u00e7\u00e3o portuguesa, Tiago sofre de cegueira total, vive no escuro desde que nasceu. No entanto Tiago n\u00e3o esconde tamb\u00e9m ele o amor\u00a0que tem por Ant\u00f3nio e diz que os gestos de ternura de Ant\u00f3nio s\u00e3o tudo o que t\u00eam de mais rico na Vida e que o complementam dia ap\u00f3s dia e reitera &#8220;posso nunca ter visto a cor dos seus olhos, mas conhe\u00e7o o seu rosto e o mais importante de tudo consegui chegar ao sitio mais profundo do cora\u00e7\u00e3o do Ant\u00f3nio e hoje sei que grande parte dos sorrisos do Ant\u00f3nio t\u00eam um pouco culpa minha &#8230;&#8221; por contra ponto o Ant\u00f3nio rapidamente reagia e dizia &#8221; n\u00e3o sejas t\u00e3o convencido cromo &#8230; tu tens um problema e sabes bem qual \u00e9 ! \u00c9 que estou perdidamente apaixonado por ti.&#8221; e sorria desalmadamente, mas passado uns segundos dizia ele em tom de sussurro &#8220;o que ele diz \u00e9 completamente verdade &#8230;&#8221;.<\/p>\n<p style=\"text-align: justify;\">A conversa durou v\u00e1rias horas e a cada momento que passava ia verificando que de facto o amor n\u00e3o escolhe idades, n\u00e3o escolhe a ra\u00e7a, n\u00e3o escolhe a perfei\u00e7\u00e3o ou a defici\u00eancia, de facto o amor \u00e9 invisual em todos estes aspectos, porque como diz o Ant\u00f3nio &#8220;o simples facto de poder prolongar cada segundo ao lado da pessoa que amo, n\u00e3o h\u00e1 dinheiro que pague tudo isto &#8230; a felicidade importa-me mais do que ter uns quantos milhares na conta banc\u00e1ria&#8221; e dizia &#8220;no principio foi complicado, porque as pessoas n\u00e3o compreendiam o porqu\u00ea de eu ter decidido dar este passo e conhecer algu\u00e9m diferente por fora, mas extraordin\u00e1rio por dentro, confesso que desfiz amizades que tinham muitos anos porque as pessoas n\u00e3o quiseram aceitar a realidade, mas n\u00e3o me arrependo um segundo daquilo que fiz dado que hoje estou com a pessoa que realmente amo e que sei que estar\u00e1 ao meu lado, talvez para o resto da Vida &#8230;&#8221; e continuava afirmando que a sociedade diz que \u00e9 aberta ao multiculturalismo e \u00e0s diferen\u00e7as dos outros, mas que o simples facto de pessoas como eles\u00a0andarem na rua de m\u00e3os dadas ou de trocarem carinhos em plena via p\u00fablica suscita alguma curiosidade nas pessoas porque n\u00e3o \u00e9 uma coisa que veem todos os dias afirmava ele. Tiago um pouco mais recatado mas em tom de brincadeira dizia &#8220;por mim podem olhar com toda a vontade porque j\u00e1 mais notarei as suas reac\u00e7\u00f5es visuais, mas quando oi\u00e7o os sussurros apercebo-me que as pessoa raramente comentam pela negativa\u0010, somos um casal como tantos outros que existem por este pa\u00eds e mundo a fora&#8221;, Ant\u00f3nio refor\u00e7ava com a ideia &#8220;n\u00e3o queremos dar nas vistas ou ser estrelas, queremos apenas passear pelas ruas como faz toda a gente, e n\u00f3s como n\u00e3o somos diferentes fazemos isso na boa !&#8221;.<\/p>\n<p style=\"text-align: justify;\">A uma certa altura perguntei-lhes qual tinha sido a coisa mais estranha que tinham feito juntos e novamente as gargalhadas vieram ao de cima, o\u00a0Ant\u00f3nio confessava que nos primeiros tempos havia coisas que era sua rotina mas que com o Tiago tudo era uma nova experi\u00eancia e dizia ele &#8220;um dia t\u00ednhamos acabado de jantar num restaurante e eu dei a ideia de irmos ao cinema e imediatamente a seguir pedi desculpa ao Tiago como se estivesse a fazer algo de errado ao que ele me respondeu que sim que deveria-mos ir, e fomos, confesso que nunca tinha tido tal experi\u00eancia de ir narrando em voz baixa ao ouvido de algu\u00e9m tudo aquilo que via na tela, certo \u00e9 que gost\u00e1mos tanto da experi\u00eancia que de vez enquanto l\u00e1 vamos n\u00f3s ao cinema ver e ouvir um filme&#8221;, j\u00e1 o Tiago diz que n\u00e3o consegue precisar uma ou v\u00e1rias hist\u00f3rias estranhas que tenha feito junto com o Ant\u00f3nio porque diz que todo aquilo que passam juntos \u00e9 \u00fanico e com um sabor aut\u00eantico\u00a0e sempre novo, mas afirma que o que mais gosta de fazer \u00e9 ir para a beira mar ou para a foz do rio e ouvir as ondas ou o som da \u00e1gua agarrado ao seu companheiro, diz que pode parecer rid\u00edculo mas \u00e9 o que os mant\u00e9m unidos e fortes para alcan\u00e7ar dia ap\u00f3s dia.<\/p>\n<p style=\"text-align: justify;\">Ao final de algumas horas de conversa fiquei com uma ideia genu\u00edna do que pode ser um amor pelo pr\u00f3ximo, genu\u00edno e livre de qualquer preconceito, a final s\u00e3o duas pessoas que se amam num n\u00edvel que talvez muitos de n\u00f3s desconhe\u00e7amos que existe, caso para deixar a pergunta no ar:<\/p>\n<h3 style=\"text-align: center;\">&#8220;N\u00e3o ser\u00e1 este um exemplo a seguir no que toca ao amor, apaixonar-mo-nos por quem sentimos algo muito especial e dedicar parte da nossa Vida sem olhar a preconceitos ou estigmas que s\u00f3 destroem o que de melhor existe na sociedade? que \u00e9 a felicidade!&#8221;<\/h3>\n<h6><\/h6>\n<h6>Por quest\u00f5es de privacidade das pessoas intervenientes nesta hist\u00f3ria, os nomes s\u00e3o fict\u00edcios e algumas informa\u00e7\u00f5es foram adulteradas de modo a que n\u00e3o afectasse o conte\u00fado da hist\u00f3ria. Toda a semelhan\u00e7a com algum caso real \u00e9 mera\u00a0coincid\u00eancia factual, esta \u00e9 uma obra ficcional inspirada em casos reais.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p class=\"excerpt\">Faz uns meses, que enquanto tomava um caf\u00e9 numa esplanada algures em Portugal tomei contacto com a hist\u00f3ria que aqui irei relatar nas pr\u00f3ximas linhas. Ser\u00e1 o amor realmente cego ? Ouvimos muitas vezes dizer que o amor n\u00e3o escolhe idades, que n\u00e3o escolhe entre ra\u00e7as e que acima de tudo n\u00e3o escolhe a perfei\u00e7\u00e3o. Pois bem achei uma hist\u00f3ria&hellip; <a href=\"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_newsletter_tier_id":0,"footnotes":"","jetpack_publicize_message":"O Amor n\u00e3o olha a estigmas ... Palavra por Palavras","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[2],"tags":[],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O Amor n\u00e3o olha a estigmas ... Palavra por Palavras<\/title>\n<meta name=\"description\" content=\"Ser\u00e1 o amor cego em todos os aspectos? Ser\u00e1 o amor uma prova factual de que a paix\u00e3o existe de formas t\u00e3o diferentes daquelas a que estamos acostumados ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O amor n\u00e3o olha a defici\u00eancias ou estigmas ... - Palavra por Palavras\" \/>\n<meta property=\"og:description\" content=\"Ser\u00e1 o amor cego em todos os aspectos? Ser\u00e1 o amor uma prova factual de que a paix\u00e3o existe de formas t\u00e3o diferentes daquelas a que estamos acostumados ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/\" \/>\n<meta property=\"og:site_name\" content=\"Palavra por Palavras\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/vasnfer\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-12T01:18:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-27T17:29:28+00:00\" \/>\n<meta name=\"author\" content=\"Vasco Ferreira\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vasco Ferreira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/\",\"url\":\"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/\",\"name\":\"O Amor n\u00e3o olha a estigmas ... Palavra por Palavras\",\"isPartOf\":{\"@id\":\"https:\/\/www.palavraporpalavras.com\/Blog\/#website\"},\"datePublished\":\"2015-09-12T01:18:40+00:00\",\"dateModified\":\"2016-05-27T17:29:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.palavraporpalavras.com\/Blog\/#\/schema\/person\/0b32a6416a3aade51ba47363143aaff8\"},\"description\":\"Ser\u00e1 o amor cego em todos os aspectos? Ser\u00e1 o amor uma prova factual de que a paix\u00e3o existe de formas t\u00e3o diferentes daquelas a que estamos acostumados ?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.palavraporpalavras.com\/Blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O amor n\u00e3o olha a defici\u00eancias ou estigmas &#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.palavraporpalavras.com\/Blog\/#website\",\"url\":\"https:\/\/www.palavraporpalavras.com\/Blog\/\",\"name\":\"Palavra por Palavras\",\"description\":\"Uma novela diferente ...\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.palavraporpalavras.com\/Blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.palavraporpalavras.com\/Blog\/#\/schema\/person\/0b32a6416a3aade51ba47363143aaff8\",\"name\":\"Vasco Ferreira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.palavraporpalavras.com\/Blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/18a1c474c8624ec6dbf928c7421dfe1b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/18a1c474c8624ec6dbf928c7421dfe1b?s=96&d=mm&r=g\",\"caption\":\"Vasco Ferreira\"},\"url\":\"https:\/\/www.palavraporpalavras.com\/Blog\/author\/vasco-ferreira\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Amor n\u00e3o olha a estigmas ... Palavra por Palavras","description":"Ser\u00e1 o amor cego em todos os aspectos? Ser\u00e1 o amor uma prova factual de que a paix\u00e3o existe de formas t\u00e3o diferentes daquelas a que estamos acostumados ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/","og_locale":"pt_PT","og_type":"article","og_title":"O amor n\u00e3o olha a defici\u00eancias ou estigmas ... - Palavra por Palavras","og_description":"Ser\u00e1 o amor cego em todos os aspectos? Ser\u00e1 o amor uma prova factual de que a paix\u00e3o existe de formas t\u00e3o diferentes daquelas a que estamos acostumados ?","og_url":"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/","og_site_name":"Palavra por Palavras","article_publisher":"http:\/\/www.facebook.com\/vasnfer","article_published_time":"2015-09-12T01:18:40+00:00","article_modified_time":"2016-05-27T17:29:28+00:00","author":"Vasco Ferreira","twitter_misc":{"Escrito por":"Vasco Ferreira","Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/","url":"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/","name":"O Amor n\u00e3o olha a estigmas ... Palavra por Palavras","isPartOf":{"@id":"https:\/\/www.palavraporpalavras.com\/Blog\/#website"},"datePublished":"2015-09-12T01:18:40+00:00","dateModified":"2016-05-27T17:29:28+00:00","author":{"@id":"https:\/\/www.palavraporpalavras.com\/Blog\/#\/schema\/person\/0b32a6416a3aade51ba47363143aaff8"},"description":"Ser\u00e1 o amor cego em todos os aspectos? Ser\u00e1 o amor uma prova factual de que a paix\u00e3o existe de formas t\u00e3o diferentes daquelas a que estamos acostumados ?","breadcrumb":{"@id":"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/09\/cenas-da-vida\/73\/o-amor-nao-olha-a-deficiencias-ou-estigmas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.palavraporpalavras.com\/Blog\/"},{"@type":"ListItem","position":2,"name":"O amor n\u00e3o olha a defici\u00eancias ou estigmas &#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.palavraporpalavras.com\/Blog\/#website","url":"https:\/\/www.palavraporpalavras.com\/Blog\/","name":"Palavra por Palavras","description":"Uma novela diferente ...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.palavraporpalavras.com\/Blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.palavraporpalavras.com\/Blog\/#\/schema\/person\/0b32a6416a3aade51ba47363143aaff8","name":"Vasco Ferreira","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.palavraporpalavras.com\/Blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/18a1c474c8624ec6dbf928c7421dfe1b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18a1c474c8624ec6dbf928c7421dfe1b?s=96&d=mm&r=g","caption":"Vasco Ferreira"},"url":"https:\/\/www.palavraporpalavras.com\/Blog\/author\/vasco-ferreira\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p7BO36-1b","jetpack-related-posts":[{"id":149,"url":"https:\/\/www.palavraporpalavras.com\/Blog\/2017\/10\/sentimentos\/149\/uma-necessidade\/","url_meta":{"origin":73,"position":0},"title":"Uma necessidade &#8230;","author":"Vasco Ferreira","date":"27 \/ Outubro \/ 2017","format":false,"excerpt":"Com o tempo, urge a necessidade de te fazer esquecer, por outro lado urge a necessidade de n\u00e3o te querer esquecer; baralhaste-me o pensamento, baralhaste por completo todas as minhas ideias e pensamentos assim como a l\u00f3gica, a que eles lhe est\u00e1 imputada toda uma ordem t\u00e9cnica e sequencial do\u2026","rel":"","context":"In &quot;Sentimentos&quot;","block_context":{"text":"Sentimentos","link":"https:\/\/www.palavraporpalavras.com\/Blog\/cat\/sentimentos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":14,"url":"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/03\/cenas-da-vida\/14\/quando-o-tempo-para\/","url_meta":{"origin":73,"position":1},"title":"Quando o tempo p\u00e1ra &#8230;","author":"Vasco Ferreira","date":"10 \/ Mar\u00e7o \/ 2015","format":false,"excerpt":"O que somos ? Quem somos ? O que fazemos ? Porque passamos a ser assunto proibido ? Porqu\u00ea \u00e9 que a o tempo parou t\u00e3o cedo ? A quando do primeiro choro, somos confrontados logo com a vari\u00e1vel das vari\u00e1veis, da qual n\u00e3o podemos escapar, a qual ser\u00e1 sempre\u2026","rel":"","context":"In &quot;Cenas da Vida&quot;","block_context":{"text":"Cenas da Vida","link":"https:\/\/www.palavraporpalavras.com\/Blog\/cat\/cenas-da-vida\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":135,"url":"https:\/\/www.palavraporpalavras.com\/Blog\/2017\/09\/sentimentos\/135\/apanhando-papeis\/","url_meta":{"origin":73,"position":2},"title":"Apanhando Pap\u00e9is","author":"Vasco Ferreira","date":"30 \/ Setembro \/ 2017","format":false,"excerpt":"A Vida por vezes \u00e9 um caos, pior que a sua defini\u00e7\u00e3o pela teoria matem\u00e1tica, que trata os sistemas complexos e din\u00e2micos rigorosamente deterministas, que representam o fen\u00f3meno da sensisibilidade \u00e0s condi\u00e7\u00f5es iniciais, que tornam a sua indetermina\u00e7\u00e3o matem\u00e1tica imposs\u00edvel no longo prazo; e se no quadrante da Vida adicionarmos\u2026","rel":"","context":"In &quot;Sentimentos&quot;","block_context":{"text":"Sentimentos","link":"https:\/\/www.palavraporpalavras.com\/Blog\/cat\/sentimentos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":162,"url":"https:\/\/www.palavraporpalavras.com\/Blog\/2018\/06\/sentimentos\/162\/o-silencio\/","url_meta":{"origin":73,"position":3},"title":"O Sil\u00eancio","author":"Vasco Ferreira","date":"9 \/ Junho \/ 2018","format":false,"excerpt":"Diz-se que o sil\u00eancio \u00e9 o bom conselheiro da sabedoria, que o sil\u00eancio da noite \u00e9 bom conselheiro, mas por vezes o sil\u00eancio pode nos reversos dos bons conselhos ser o porto de abrigo para o perigoso caminho das tormentas, conhecidas e desconhecidas. O sil\u00eancio da voz, a mudez dos\u2026","rel":"","context":"In &quot;Sentimentos&quot;","block_context":{"text":"Sentimentos","link":"https:\/\/www.palavraporpalavras.com\/Blog\/cat\/sentimentos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":169,"url":"https:\/\/www.palavraporpalavras.com\/Blog\/2019\/05\/cenas-da-vida\/169\/uma-talvez-ao-luar\/","url_meta":{"origin":73,"position":4},"title":"Um talvez ao luar","author":"Vasco Ferreira","date":"25 \/ Maio \/ 2019","format":false,"excerpt":"J\u00e1 perdi a conta \u00e0s vezes, aos dias, \u00e0s situa\u00e7\u00f5es que me levaram a vir para aqui puramente pensar na Vida, ou escrever aquilo que me ia na alma, de entre todas essas vezes apenas em duas situa\u00e7\u00f5es estive aqui acompanhado, por isso posso dizer que n\u00e3o raras mas rar\u00edssimas\u2026","rel":"","context":"In &quot;Cenas da Vida&quot;","block_context":{"text":"Cenas da Vida","link":"https:\/\/www.palavraporpalavras.com\/Blog\/cat\/cenas-da-vida\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":49,"url":"https:\/\/www.palavraporpalavras.com\/Blog\/2015\/06\/sociedade\/49\/os-julgamentos\/","url_meta":{"origin":73,"position":5},"title":"Os Julgamentos &#8230;","author":"Vasco Ferreira","date":"4 \/ Junho \/ 2015","format":false,"excerpt":"Fa\u00e7amos hoje a seguinte interroga\u00e7\u00e3o, de que maneira influenciam os nossos preceitos e conceitos o modo como viv\u00eancia-mos a experi\u00eancia com a sociedade que nos rodeia ? Ser\u00e1 esta considerada uma pergunta descabida para a maior parte das pessoas, fa\u00e7o eu a interroga\u00e7\u00e3o ? Com a evolu\u00e7\u00e3o do mundo moderno\u2026","rel":"","context":"In &quot;Sociedade&quot;","block_context":{"text":"Sociedade","link":"https:\/\/www.palavraporpalavras.com\/Blog\/cat\/sociedade\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.palavraporpalavras.com\/Blog\/wp-json\/wp\/v2\/posts\/73"}],"collection":[{"href":"https:\/\/www.palavraporpalavras.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palavraporpalavras.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palavraporpalavras.com\/Blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palavraporpalavras.com\/Blog\/wp-json\/wp\/v2\/comments?post=73"}],"version-history":[{"count":0,"href":"https:\/\/www.palavraporpalavras.com\/Blog\/wp-json\/wp\/v2\/posts\/73\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.palavraporpalavras.com\/Blog\/wp-json\/wp\/v2\/media?parent=73"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palavraporpalavras.com\/Blog\/wp-json\/wp\/v2\/categories?post=73"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palavraporpalavras.com\/Blog\/wp-json\/wp\/v2\/tags?post=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}